{"id":4266,"date":"2024-09-30T17:51:28","date_gmt":"2024-09-30T15:51:28","guid":{"rendered":"https:\/\/dev2.saihydraulics.com\/soluzioni\/horizontal-drilling-machine\/"},"modified":"2024-12-03T11:03:16","modified_gmt":"2024-12-03T10:03:16","slug":"horizontal-drilling-machine","status":"publish","type":"soluzioni","link":"https:\/\/dev2.saihydraulics.com\/en\/solutions\/horizontal-drilling-machine\/","title":{"rendered":"Horizontal drilling machines"},"content":{"rendered":"","protected":false},"template":"","applicazione":[64],"class_list":["post-4266","soluzioni","type-soluzioni","status-publish","hentry","applicazione-perforation"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Horizontal drilling machines - SAI Hydraulic Motors<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dev2.saihydraulics.com\/en\/solutions\/horizontal-drilling-machine\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Horizontal drilling machines - SAI Hydraulic Motors\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dev2.saihydraulics.com\/en\/solutions\/horizontal-drilling-machine\/\" \/>\n<meta property=\"og:site_name\" content=\"SAI Hydraulic Motors\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-03T10:03:16+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dev2.saihydraulics.com\/en\/solutions\/horizontal-drilling-machine\/\",\"url\":\"https:\/\/dev2.saihydraulics.com\/en\/solutions\/horizontal-drilling-machine\/\",\"name\":\"Horizontal drilling machines - SAI Hydraulic Motors\",\"isPartOf\":{\"@id\":\"https:\/\/dev2.saihydraulics.com\/en\/#website\"},\"datePublished\":\"2024-09-30T15:51:28+00:00\",\"dateModified\":\"2024-12-03T10:03:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/dev2.saihydraulics.com\/en\/solutions\/horizontal-drilling-machine\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dev2.saihydraulics.com\/en\/solutions\/horizontal-drilling-machine\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dev2.saihydraulics.com\/en\/solutions\/horizontal-drilling-machine\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/dev2.saihydraulics.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Soluzioni\",\"item\":\"https:\/\/dev2.saihydraulics.com\/en\/solutions\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Horizontal drilling machines\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dev2.saihydraulics.com\/en\/#website\",\"url\":\"https:\/\/dev2.saihydraulics.com\/en\/\",\"name\":\"%%sitename%%\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/dev2.saihydraulics.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dev2.saihydraulics.com\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/dev2.saihydraulics.com\/en\/#organization\",\"name\":\"%%sitename%%\",\"url\":\"https:\/\/dev2.saihydraulics.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/dev2.saihydraulics.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dev2.saihydraulics.com\/wp-content\/uploads\/2024\/09\/saiLogo-1-1.png\",\"contentUrl\":\"https:\/\/dev2.saihydraulics.com\/wp-content\/uploads\/2024\/09\/saiLogo-1-1.png\",\"width\":132,\"height\":49,\"caption\":\"%%sitename%%\"},\"image\":{\"@id\":\"https:\/\/dev2.saihydraulics.com\/en\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Horizontal drilling machines - SAI Hydraulic Motors","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dev2.saihydraulics.com\/en\/solutions\/horizontal-drilling-machine\/","og_locale":"en_US","og_type":"article","og_title":"Horizontal drilling machines - SAI Hydraulic Motors","og_url":"https:\/\/dev2.saihydraulics.com\/en\/solutions\/horizontal-drilling-machine\/","og_site_name":"SAI Hydraulic Motors","article_modified_time":"2024-12-03T10:03:16+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dev2.saihydraulics.com\/en\/solutions\/horizontal-drilling-machine\/","url":"https:\/\/dev2.saihydraulics.com\/en\/solutions\/horizontal-drilling-machine\/","name":"Horizontal drilling machines - SAI Hydraulic Motors","isPartOf":{"@id":"https:\/\/dev2.saihydraulics.com\/en\/#website"},"datePublished":"2024-09-30T15:51:28+00:00","dateModified":"2024-12-03T10:03:16+00:00","breadcrumb":{"@id":"https:\/\/dev2.saihydraulics.com\/en\/solutions\/horizontal-drilling-machine\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dev2.saihydraulics.com\/en\/solutions\/horizontal-drilling-machine\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dev2.saihydraulics.com\/en\/solutions\/horizontal-drilling-machine\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dev2.saihydraulics.com\/en\/"},{"@type":"ListItem","position":2,"name":"Soluzioni","item":"https:\/\/dev2.saihydraulics.com\/en\/solutions\/"},{"@type":"ListItem","position":3,"name":"Horizontal drilling machines"}]},{"@type":"WebSite","@id":"https:\/\/dev2.saihydraulics.com\/en\/#website","url":"https:\/\/dev2.saihydraulics.com\/en\/","name":"%%sitename%%","description":"","publisher":{"@id":"https:\/\/dev2.saihydraulics.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dev2.saihydraulics.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/dev2.saihydraulics.com\/en\/#organization","name":"%%sitename%%","url":"https:\/\/dev2.saihydraulics.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/dev2.saihydraulics.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/dev2.saihydraulics.com\/wp-content\/uploads\/2024\/09\/saiLogo-1-1.png","contentUrl":"https:\/\/dev2.saihydraulics.com\/wp-content\/uploads\/2024\/09\/saiLogo-1-1.png","width":132,"height":49,"caption":"%%sitename%%"},"image":{"@id":"https:\/\/dev2.saihydraulics.com\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/dev2.saihydraulics.com\/en\/wp-json\/wp\/v2\/soluzioni\/4266","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev2.saihydraulics.com\/en\/wp-json\/wp\/v2\/soluzioni"}],"about":[{"href":"https:\/\/dev2.saihydraulics.com\/en\/wp-json\/wp\/v2\/types\/soluzioni"}],"wp:attachment":[{"href":"https:\/\/dev2.saihydraulics.com\/en\/wp-json\/wp\/v2\/media?parent=4266"}],"wp:term":[{"taxonomy":"applicazione","embeddable":true,"href":"https:\/\/dev2.saihydraulics.com\/en\/wp-json\/wp\/v2\/applicazione?post=4266"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}